{"id":1267,"date":"2015-12-20T15:31:13","date_gmt":"2015-12-20T14:31:13","guid":{"rendered":"http:\/\/www.paroisse-saint-charles.fr\/?p=1267"},"modified":"2015-12-20T21:27:20","modified_gmt":"2015-12-20T20:27:20","slug":"annonces-du-dimanche-20-decembre","status":"publish","type":"post","link":"https:\/\/paroisse-saint-charles.fr\/WordPress3\/2015\/12\/annonces-du-dimanche-20-decembre\/","title":{"rendered":"Annonces du dimanche 20 d\u00e9cembre."},"content":{"rendered":"<p>Chers paroissiens,<\/p>\n<p>notez que cette semaine, il n&rsquo;y aura <strong>pas de messe ce lundi 21 (f\u00eate de saint Thomas) et ce mardi<\/strong>.<\/p>\n<p>Mercredi 23, <strong>r\u00e9p\u00e9tition du conte de No\u00ebl \u00e0 16h. <\/strong>messe \u00e0 18h, v\u00eapres \u00e0 18h30.<strong> R\u00e9p\u00e9tition de chorale \u00e0 20h<\/strong>.<\/p>\n<p>Jeudi 24, messe de la vigile de No\u00ebl \u00e0 12h15. 1\u00e8res v\u00eapres de No\u00ebl \u00e0 18h30. Matines de No\u00ebl \u00e0 20h. r\u00e9p\u00e9tition de chorale et du conte de No\u00ebl \u00e0 22h30. <span style=\"text-decoration: underline;\"><strong>Veill\u00e9e de No\u00ebl \u00e0 23h, messe de No\u00ebl \u00e0 minuit<\/strong><\/span>.<\/p>\n<p>Vendredi 25, messe \u00e0 9h et <strong>grand-messe \u00e0 10h30<\/strong>.<\/p>\n<p><strong>Confessions<\/strong> : le mercredi de 16h \u00e0 18h, jeudi de 10h \u00e0 12h et de 15h \u00e0 18h30.<\/p>\n<p>samedi 26, messe \u00e0 18h.<\/p>\n<p>Merci de poursuivre l&rsquo;accueil des nouveaux venus et en particuliers des cat\u00e9chum\u00e8nes !<\/p>\n<p>Pensez \u00e0 r\u00e9cup\u00e9rer vos plats et autres Tupperware laiss\u00e9s \u00e0 la sacristie. Pensez \u00e0 marquer votre nom dans vos missels (ainsi que dans les jaquettes de vos missels).<\/p>\n<p>En vous assurant de nos pri\u00e8res<\/p>\n<p>Abb\u00e9 Eloi Gillet<br \/>\nAbb\u00e9 Florent Molin<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chers paroissiens, notez que cette semaine, il n&rsquo;y aura pas de messe ce lundi 21 (f\u00eate de saint Thomas) et ce mardi. Mercredi 23, r\u00e9p\u00e9tition du conte de No\u00ebl \u00e0 16h. messe \u00e0 18h, v\u00eapres \u00e0 18h30. R\u00e9p\u00e9tition de chorale&#8230;<br \/><a class=\"read-more-button\" href=\"https:\/\/paroisse-saint-charles.fr\/WordPress3\/2015\/12\/annonces-du-dimanche-20-decembre\/\">Savoir plus<\/a><\/p>\n","protected":false},"author":4,"featured_media":1271,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,11],"tags":[],"class_list":["post-1267","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-homepage","category-newsletter"],"jetpack_featured_media_url":"https:\/\/paroisse-saint-charles.fr\/WordPress3\/wp-content\/uploads\/2015\/12\/AfficheNoel2015_Mini.jpg","_links":{"self":[{"href":"https:\/\/paroisse-saint-charles.fr\/WordPress3\/wp-json\/wp\/v2\/posts\/1267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paroisse-saint-charles.fr\/WordPress3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/paroisse-saint-charles.fr\/WordPress3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/paroisse-saint-charles.fr\/WordPress3\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/paroisse-saint-charles.fr\/WordPress3\/wp-json\/wp\/v2\/comments?post=1267"}],"version-history":[{"count":1,"href":"https:\/\/paroisse-saint-charles.fr\/WordPress3\/wp-json\/wp\/v2\/posts\/1267\/revisions"}],"predecessor-version":[{"id":1268,"href":"https:\/\/paroisse-saint-charles.fr\/WordPress3\/wp-json\/wp\/v2\/posts\/1267\/revisions\/1268"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/paroisse-saint-charles.fr\/WordPress3\/wp-json\/wp\/v2\/media\/1271"}],"wp:attachment":[{"href":"https:\/\/paroisse-saint-charles.fr\/WordPress3\/wp-json\/wp\/v2\/media?parent=1267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/paroisse-saint-charles.fr\/WordPress3\/wp-json\/wp\/v2\/categories?post=1267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/paroisse-saint-charles.fr\/WordPress3\/wp-json\/wp\/v2\/tags?post=1267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}